{"id":37309,"date":"2026-07-15T18:48:33","date_gmt":"2026-07-15T18:48:33","guid":{"rendered":"https:\/\/www.zolattitude.com\/index.php\/2026\/07\/15\/le-squelette-gardien-cache-a-linterieur-des-cellules-cerebrales-pourrait-aider-a-combattre-la-maladie-dalzheimer\/"},"modified":"2026-07-15T18:48:33","modified_gmt":"2026-07-15T18:48:33","slug":"le-squelette-gardien-cache-a-linterieur-des-cellules-cerebrales-pourrait-aider-a-combattre-la-maladie-dalzheimer","status":"publish","type":"post","link":"https:\/\/www.zolattitude.com\/index.php\/2026\/07\/15\/le-squelette-gardien-cache-a-linterieur-des-cellules-cerebrales-pourrait-aider-a-combattre-la-maladie-dalzheimer\/","title":{"rendered":"Le squelette \u00ab gardien \u00bb cach\u00e9 \u00e0 l\u2019int\u00e9rieur des cellules c\u00e9r\u00e9brales pourrait aider \u00e0 combattre la maladie d\u2019Alzheimer"},"content":{"rendered":"<p><\/p>\n<p id=\"first\">Les cellules c\u00e9r\u00e9brales extraient continuellement des mat\u00e9riaux du fluide qui les entoure, notamment des nutriments, des mol\u00e9cules de signalisation et des fragments de leurs propres surfaces externes. Ce processus, appel\u00e9 endocytose, soutient l\u2019apprentissage, la m\u00e9moire et l\u2019entretien courant des neurones.<\/p>\n<div id=\"text\">\n<p>Les chercheurs de Penn State ont maintenant identifi\u00e9 une structure jusqu\u2019alors m\u00e9connue qui pourrait contr\u00f4ler une grande partie de cette activit\u00e9. La structure est un r\u00e9seau situ\u00e9 juste sous la surface des neurones et est connue sous le nom de squelette p\u00e9riodique associ\u00e9 \u00e0 la membrane, ou MPS.<\/p>\n<p><strong>Un gardien cach\u00e9 \u00e0 l\u2019int\u00e9rieur des neurones<\/strong><\/p>\n<p>Dans les r\u00e9sultats publi\u00e9s dans <em>Avanc\u00e9es scientifiques<\/em>l&#8217;\u00e9quipe a montr\u00e9 que le MPS agit comme un gardien physique pour presque tous les principaux types d&#8217;endocytose. Construite \u00e0 partir d\u2019anneaux r\u00e9p\u00e9titifs de prot\u00e9ines, cette structure \u00e9tait d\u00e9j\u00e0 connue pour aider les neurones \u00e0 conserver leur forme. Les nouveaux r\u00e9sultats indiquent qu\u2019il joue \u00e9galement un r\u00f4le beaucoup plus actif en contr\u00f4lant o\u00f9 et quand les substances p\u00e9n\u00e8trent dans la cellule.<\/p>\n<p>&#8220;Depuis de tr\u00e8s nombreuses ann\u00e9es, nous essayons de comprendre ce m\u00e9canisme mol\u00e9culaire, quel type de machinerie contribuera \u00e0 faciliter ce processus, car il est li\u00e9 aux maladies neurod\u00e9g\u00e9n\u00e9ratives&#8221;, a d\u00e9clar\u00e9 Ruobo Zhou, professeur adjoint de chimie, de biochimie et de biologie mol\u00e9culaire, et de g\u00e9nie biom\u00e9dical, \u00e0 Penn State et auteur correspondant de l&#8217;\u00e9tude. &#8220;Lorsque l&#8217;endocytose &#8211; cette absorption et cette r\u00e9gulation des nutriments &#8211; tourne mal, il y a alors une agr\u00e9gation de prot\u00e9ines qui s&#8217;accumule dans le cerveau, ce qui est la marque des maladies neurod\u00e9g\u00e9n\u00e9ratives telles que la maladie d&#8217;Alzheimer et la maladie de Parkinson.&#8221;<\/p>\n<p>Zhou a aid\u00e9 \u00e0 d\u00e9couvrir le MPS en 2013 alors qu&#8217;il travaillait comme chercheur postdoctoral dans une \u00e9quipe de Harvard. \u00c0 l\u2019\u00e9poque, les scientifiques pensaient que la structure servait principalement de syst\u00e8me de soutien interne passif. Dans la nouvelle \u00e9tude, Zhou et ses coll\u00e8gues ont utilis\u00e9 l&#8217;imagerie \u00e0 super-r\u00e9solution sur des neurones cultiv\u00e9s en laboratoire et ont d\u00e9couvert que le MPS se comporte davantage comme un contr\u00f4leur de trafic cellulaire, r\u00e9gulant toutes les principales formes d&#8217;endocytose.<\/p>\n<p><strong>Observer l\u2019absorption cellulaire \u00e0 l\u2019\u00e9chelle nanom\u00e9trique<\/strong><\/p>\n<p>Les chercheurs se sont appuy\u00e9s sur la microscopie avanc\u00e9e \u00e0 super-r\u00e9solution, qui peut r\u00e9v\u00e9ler des structures \u00e0 l&#8217;\u00e9chelle nanom\u00e9trique, environ 10 000 fois plus petites que l&#8217;\u00e9paisseur d&#8217;un cheveu humain. Ils ont \u00e9tudi\u00e9 les neurones cultiv\u00e9s dans des bo\u00eetes de P\u00e9tri et ont provoqu\u00e9 la formation de prot\u00e9ines s\u00e9lectionn\u00e9es \u00e0 l\u2019int\u00e9rieur des cellules afin que ces prot\u00e9ines puissent \u00eatre suivies.<\/p>\n<p>Les scientifiques ont ensuite expos\u00e9 les neurones \u00e0 diff\u00e9rentes mol\u00e9cules et observ\u00e9 comment les cellules les absorbaient alors que le MPS restait intact. Ils ont \u00e9galement modifi\u00e9 la structure en endommageant ou en prot\u00e9geant des sections sp\u00e9cifiques, leur permettant ainsi de voir comment les neurones r\u00e9agissaient lorsque le r\u00e9seau changeait.<\/p>\n<p>Lorsque le MPS a \u00e9t\u00e9 perturb\u00e9, les neurones ont commenc\u00e9 \u00e0 absorber la mati\u00e8re beaucoup plus rapidement. Cela indique que le r\u00e9seau ralentit normalement le processus et emp\u00eache une absorption excessive.<\/p>\n<p>Les chercheurs ont \u00e9galement d\u00e9couvert que la structure peut contribuer \u00e0 sa propre d\u00e9gradation. Une endocytose plus rapide a affaibli le r\u00e9seau et d\u00e9clench\u00e9 une boucle de r\u00e9troaction positive. Une absorption accrue activait des signaux mol\u00e9culaires qui dirigeaient les prot\u00e9ines \u00e0 l\u2019int\u00e9rieur des neurones pour couper des sections du squelette. Cela a ouvert des points d\u2019entr\u00e9e suppl\u00e9mentaires et permis \u00e0 encore plus de nutriments et de prot\u00e9ines d\u2019entrer.<\/p>\n<p>&#8220;Nous avons d\u00e9couvert que ce squelette membranaire r\u00e9gule activement le processus d&#8217;absorption des nutriments par les neurones&#8221;, a d\u00e9clar\u00e9 Zhou. &#8220;Vous pouvez le consid\u00e9rer comme un gardien, gardant cette barri\u00e8re physique pour emp\u00eacher l&#8217;absorption des nutriments. Lorsqu&#8217;un neurone a besoin d&#8217;absorber un nutriment sp\u00e9cifique, ce gardien ouvrira les portes et le laissera entrer.&#8221;<\/p>\n<p>Zhou a expliqu\u00e9 que cette flexibilit\u00e9 peut permettre aux neurones d&#8217;augmenter leur activit\u00e9 lorsqu&#8217;ils doivent r\u00e9agir rapidement. Cependant, ce m\u00eame m\u00e9canisme pourrait devenir n\u00e9faste s\u2019il n\u2019est plus correctement ma\u00eetris\u00e9.<\/p>\n<p><strong>Un lien possible avec la maladie d&#8217;Alzheimer<\/strong><\/p>\n<p>Pour \u00e9tudier cette possibilit\u00e9, les chercheurs ont cr\u00e9\u00e9 des exp\u00e9riences cellulaires qui ressemblaient aux premiers stades de la maladie d&#8217;Alzheimer. Ils ont amen\u00e9 les neurones \u00e0 produire des niveaux plus \u00e9lev\u00e9s de prot\u00e9ine pr\u00e9curseur amylo\u00efde (APP), un marqueur cl\u00e9 associ\u00e9 \u00e0 la maladie.<\/p>\n<p>L\u2019affaiblissement du MPS a amen\u00e9 les neurones \u00e0 absorber l\u2019APP plus rapidement. Apr\u00e8s avoir p\u00e9n\u00e9tr\u00e9 dans les cellules, l&#8217;APP a \u00e9t\u00e9 d\u00e9coup\u00e9e en amylo\u00efde-B42, un fragment toxique fortement associ\u00e9 \u00e0 la maladie d&#8217;Alzheimer. Les neurones pr\u00e9sentant une MPS endommag\u00e9e accumulaient des quantit\u00e9s croissantes de cette mol\u00e9cule nocive et pr\u00e9sentaient davantage de marqueurs de mort cellulaire.<\/p>\n<p>&#8220;Nous avons cr\u00e9\u00e9 un mod\u00e8le qui ressemble beaucoup \u00e0 la maladie d&#8217;Alzheimer et avons d\u00e9couvert que dans certains neurones vieillissants ou dans des conditions pathologiques, l&#8217;endocytose de prot\u00e9ines toxiques \u00e9tait renforc\u00e9e, ce qui provoquait des conditions de stress conduisant finalement \u00e0 la mort des neurones&#8221;, a d\u00e9clar\u00e9 Jinyu Fei, \u00e9tudiant dipl\u00f4m\u00e9 du d\u00e9partement de chimie de l&#8217;Eberly College of Science de Penn State et auteur principal de l&#8217;\u00e9tude.<\/p>\n<p><strong>Une nouvelle cible potentielle de traitement<\/strong><\/p>\n<p>Les r\u00e9sultats sugg\u00e8rent que la MPS pourrait agir comme une barri\u00e8re protectrice dans les neurones en ralentissant l&#8217;absorption de l&#8217;APP et en limitant l&#8217;accumulation de mol\u00e9cules toxiques. Comme on sait que la structure se d\u00e9t\u00e9riore au cours du vieillissement et des maladies neurod\u00e9g\u00e9n\u00e9ratives, sa d\u00e9gradation pourrait pousser les neurones dans un cycle dommageable impliquant une plus grande production d\u2019amylo\u00efde, un affaiblissement structurel suppl\u00e9mentaire et, \u00e0 terme, la mort cellulaire.<\/p>\n<p>Les chercheurs ont d\u00e9clar\u00e9 que la protection ou la stabilisation de ce r\u00e9seau pourrait offrir une nouvelle fa\u00e7on de ralentir la neurod\u00e9g\u00e9n\u00e9rescence.<\/p>\n<p>&#8220;Nous pensons que cela pourrait ouvrir la porte \u00e0 de futures th\u00e9rapies telles qu&#8217;une cible prot\u00e9ique pour le traitement des maladies neurod\u00e9g\u00e9n\u00e9ratives&#8221;, a d\u00e9clar\u00e9 Fei. &#8220;La pr\u00e9servation ou la stabilisation du MPS pourrait offrir un moyen de ralentir les changements cellulaires pr\u00e9coces et cach\u00e9s qui pr\u00e9c\u00e8dent les sympt\u00f4mes de la maladie d&#8217;Alzheimer.&#8221;<\/p>\n<p><em>Les autres auteurs de l&#8217;article sont Yuanmin Zheng, doctorant en g\u00e9nie biom\u00e9dical ; Caden LaLonde, \u00e9tudiant de quatri\u00e8me ann\u00e9e de premier cycle avec sp\u00e9cialisation en biochimie et biologie mol\u00e9culaire ; et Yuan Tao, \u00e9tudiant dipl\u00f4m\u00e9 aux Huck Institutes of Life Sciences de Penn State.<\/em><\/p>\n<p><em>Les National Institutes of Health ont financ\u00e9 ce travail.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les cellules c\u00e9r\u00e9brales extraient continuellement des mat\u00e9riaux du fluide qui les entoure, notamment des nutriments, des mol\u00e9cules de signalisation et des fragments de leurs propres surfaces externes. Ce processus, appel\u00e9 endocytose, soutient l\u2019apprentissage, la m\u00e9moire et l\u2019entretien courant des neurones. Les chercheurs de Penn State ont maintenant identifi\u00e9 une structure jusqu\u2019alors m\u00e9connue qui pourrait contr\u00f4ler [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"fifu_image_url":"https:\/\/www.sciencedaily.com\/images\/1920\/neuron-brain-cell-signal-transmission.webp","fifu_image_alt":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[159],"tags":[689,1478,1996,2398,663,1923,651,8966,1035,1699,962,8965],"offerexpiration":[],"class_list":["post-37309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themes-de-sante","tag-aider","tag-cache","tag-cellules","tag-cerebrales","tag-combattre","tag-dalzheimer","tag-des","tag-gardien","tag-linterieur","tag-maladie","tag-pourrait","tag-squelette"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.sciencedaily.com\/images\/1920\/neuron-brain-cell-signal-transmission.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/posts\/37309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/comments?post=37309"}],"version-history":[{"count":0,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/posts\/37309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/media\/37310"}],"wp:attachment":[{"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/media?parent=37309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/categories?post=37309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/tags?post=37309"},{"taxonomy":"offerexpiration","embeddable":true,"href":"https:\/\/www.zolattitude.com\/index.php\/wp-json\/wp\/v2\/offerexpiration?post=37309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}